{"id":596,"date":"2026-06-29T19:37:22","date_gmt":"2026-06-29T19:37:22","guid":{"rendered":"https:\/\/heales.org\/healeses\/?p=596"},"modified":"2026-06-29T19:37:32","modified_gmt":"2026-06-29T19:37:32","slug":"boletin-mensual-de-heales-la-muerte-de-la-muerte-n-o-206","status":"publish","type":"post","link":"https:\/\/heales.org\/healeses\/2026\/06\/29\/boletin-mensual-de-heales-la-muerte-de-la-muerte-n-o-206\/","title":{"rendered":"Bolet\u00edn mensual de Heales La muerte de la muerte N.\u00ba 206"},"content":{"rendered":"<hr \/>\n<p><i><\/i><i><span style=\"font-weight: 400;\">Creo que el envejecimiento es una enfermedad. Creo que es tratable. Creo que podemos tratarla durante nuestras vidas. (&#8230;) No importa que podamos prolongar la esperanza de vida si no podemos prolongar la esperanza de vida saludable en la misma medida.<\/span><\/i> <a href=\"https:\/\/en.wikipedia.org\/wiki\/David_A._Sinclair\"><span style=\"font-weight: 400;\">David Sinclair<\/span><\/a><span style=\"font-weight: 400;\"> (bi\u00f3logo australiano) <\/span><a href=\"https:\/\/www.goodreads.com\/work\/quotes\/68047297-lifespan-why-we-age-and-why-we-don-t-have-to\"><span style=\"font-weight: 400;\">Fuente<\/span><\/a><\/p>\n<hr \/>\n<p><span>Tema de este mes: Resultados de la encuesta sobre la longevidad con <\/span><a href=\"https:\/\/www.niradata.com\/\"><span>datos de Nira<\/span><\/a><\/p>\n<hr \/>\n<p><b>Si nuevos tratamientos m\u00e9dicos permitieran que la gente en general viviera d\u00e9cadas m\u00e1s con buena salud, \u00bfla gente realmente querr\u00eda eso?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La idea de prolongar dr\u00e1sticamente la esperanza de vida humana ha ocupado durante mucho tiempo un lugar peculiar en el discurso p\u00fablico. Para algunos, representa una de las mayores oportunidades de la humanidad: la posibilidad de eliminar las enfermedades relacionadas con la edad y sumar d\u00e9cadas de vida saludable. Para otros, plantea preguntas inquietantes sobre la desigualdad, el sentido de la vida, el poder y la futura estructura de la sociedad. Una nueva encuesta global sugiere que ambas perspectivas siguen muy vigentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando se les pregunt\u00f3 si ser\u00eda deseable que nuevos tratamientos m\u00e9dicos permitieran que la gente en general viviera d\u00e9cadas m\u00e1s con buena salud, el 51% de los encuestados a nivel mundial respondi\u00f3 que s\u00ed. El 24% dijo que no, mientras que el 25% afirm\u00f3 no estar seguro. La conclusi\u00f3n es clara: la mayor\u00eda apoya la idea. Lo que hay detr\u00e1s es que ese apoyo sigue siendo sorprendentemente fr\u00e1gil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los resultados se basan en una encuesta en l\u00ednea a gran escala realizada por Nira Data entre el 19 de marzo y el 21 de abril de 2026. El estudio recopil\u00f3 respuestas de 377.458 adultos de 18 a\u00f1os o m\u00e1s en 104 pa\u00edses, lo que proporcion\u00f3 una amplia perspectiva global sobre el tema. El formato en l\u00ednea permiti\u00f3 una amplia cobertura geogr\u00e1fica y una muestra internacional diversa. Se puede acceder a los datos sin procesar <\/span><a href=\"https:\/\/d1w7u4320r496l.cloudfront.net\/omnibus\/radical-life-extension.html?Expires=4932970043&amp;Signature=L0iQv1B6hPvbToAsWCcl~pHIY19vCLcXlSsZN9eVxyWWYuQpkaUr3qKPBo6lpPe1tBho4yoLOLuxomUpc6C9mn42Z0~c0a6FjvN64cOjmwv~OHEICkRTliPxM0FdyJlg76AIwu4AAnA-tbcTvoNnTUEW9DRkHf8wPzVKnvu-rckoQN4DCuujyg-wlBPPa~HVCUsyu~HCT-spq5RmohYaEPJV3GNnyVDyMw8bFVTlQMXJvInF8qZalyggG8RuhdTydtztYivF-mnVNNgTqcutBGGAkWECybb2uLDPbUjtHD8Ey1NhU3dl22hi7-k8JQiqe1GVrUTPL7c2w3gwJSU~fg__&amp;Key-Pair-Id=KZ8ZZK6Y03P02\"><span style=\"font-weight: 400;\">aqu\u00ed<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A pesar de presentarse de la manera quiz\u00e1s m\u00e1s favorable posible \u2014 una vida m\u00e1s larga, buena salud, acceso para la persona promedio \u2014 el concepto solo atrae a una escasa mayor\u00eda. Una de cada cuatro personas sigue indecisa.<\/span><\/p>\n<h2><b>La cifra m\u00e1s importante es probablemente el 25%<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Una cuarta parte de los encuestados seleccion\u00f3 \u00abno estoy seguro\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En las investigaciones de opini\u00f3n p\u00fablica, las grandes poblaciones indecisas suelen indicar que las personas a\u00fan no han formado opiniones estables. Esto es significativo porque la longevidad sigue siendo un concepto relativamente nuevo para la mayor\u00eda de los ciudadanos. Pocas personas han dedicado mucho tiempo a considerar las consecuencias sociales de agregar d\u00e9cadas a la esperanza de vida promedio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La encuesta sugiere que, si bien la gente comprende en t\u00e9rminos generales los beneficios personales de una mejor salud, sigue sin estar segura acerca de las implicaciones sociales de una vida mucho m\u00e1s larga.<\/span><\/p>\n<h2><b>Est\u00e1 surgiendo un consenso global<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Uno de los hallazgos m\u00e1s llamativos es cu\u00e1n consistente es el apoyo en todas las regiones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todas las regiones encuestadas se muestran netamente a favor de la extensi\u00f3n radical de la vida. Europa se perfila como la regi\u00f3n m\u00e1s favorable, ligeramente por delante de las Am\u00e9ricas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ese resultado puede sorprender a los observadores que suelen caracterizar a los europeos como m\u00e1s cautelosos ante las tecnolog\u00edas emergentes. Sin embargo, cuando la longevidad se plantea como una intervenci\u00f3n de salud p\u00fablica en lugar de una tecnolog\u00eda disruptiva, se alinea naturalmente con los valores relacionados con la prevenci\u00f3n de enfermedades, el bienestar y el envejecimiento saludable.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las Am\u00e9ricas muestran niveles de apoyo casi id\u00e9nticos, lo que refleja una combinaci\u00f3n de optimismo hacia la innovaci\u00f3n m\u00e9dica y un fuerte inter\u00e9s en los resultados de salud personales. El resultado positivo de \u00c1frica subsahariana es particularmente notable. A pesar de enfrentar desaf\u00edos de salud p\u00fablica m\u00e1s inmediatos que las regiones m\u00e1s ricas, los encuestados siguen siendo muy receptivos a la perspectiva de prolongar la vida saludable. Las regiones de Asia-Pac\u00edfico y Oriente Medio\/\u00c1frica del Norte muestran un entusiasmo algo menor, aunque ambas siguen siendo claramente a favor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La tendencia general es importante: el apoyo a la longevidad no se limita a una civilizaci\u00f3n, cultura o bloque econ\u00f3mico en particular. Las diferencias se refieren en gran medida a la intensidad m\u00e1s que a la direcci\u00f3n. Ninguna regi\u00f3n rechaza el concepto de plano.<\/span><\/p>\n<h2><b>El futuro pertenece a quienes creen que tienen uno<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Los datos demogr\u00e1ficos revelan quiz\u00e1s la conclusi\u00f3n m\u00e1s profunda de la encuesta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El apoyo a la longevidad es m\u00e1s fuerte entre las personas que est\u00e1n econ\u00f3micamente activas, socialmente integradas y son optimistas respecto a su futuro.<\/span><\/p>\n<h3><b>El patr\u00f3n de edad desaf\u00eda las expectativas<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Contrario a lo que se suele suponer, el mayor apoyo no proviene de los adultos j\u00f3venes. Los encuestados de mediana edad son el grupo que m\u00e1s apoya la idea en la encuesta. Esto tiene sentido desde un punto de vista intuitivo. Las personas de entre cuarenta y cincuenta a\u00f1os tienen la edad suficiente para sentir la realidad del envejecimiento, pero son lo suficientemente j\u00f3venes como para esperar beneficiarse de futuros avances m\u00e9dicos. Para ellos, la longevidad no es un experimento mental. Es algo personal. Este hallazgo tambi\u00e9n desmiente la narrativa com\u00fan de que los adultos mayores se oponen a las tecnolog\u00edas transformadoras. Los encuestados mayores de 56 a\u00f1os siguen mostr\u00e1ndose muy positivos cuando la discusi\u00f3n se centra en los a\u00f1os de buena salud en lugar de simplemente en vivir m\u00e1s a\u00f1os.<\/span><\/p>\n<h3><b>La educaci\u00f3n crea una gran brecha<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">La educaci\u00f3n es uno de los factores que mejor predice el apoyo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un menor nivel educativo se corresponde con un entusiasmo considerablemente menor. Esto puede reflejar diferencias en la confianza hacia las instituciones cient\u00edficas, las expectativas de acceso o actitudes m\u00e1s amplias hacia el cambio tecnol\u00f3gico. Es importante destacar que un menor apoyo no debe interpretarse necesariamente como hostilidad hacia la longevidad en s\u00ed misma. En cambio, puede reflejar escepticismo sobre si dichos avances ser\u00edan accesibles o beneficiosos para la gente com\u00fan.<\/span><\/p>\n<h3><b>Los trabajadores a tiempo completo apuntan el camino<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">La situaci\u00f3n laboral revela uno de los patrones m\u00e1s claros de la encuesta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los trabajadores a tiempo completo se encuentran entre los grupos que m\u00e1s apoyo brindan en general. Para las personas profundamente involucradas en la vida econ\u00f3mica, los a\u00f1os adicionales de buena salud pueden traducirse f\u00e1cilmente en aspiraciones familiares:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">M\u00e1s a\u00f1os productivos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">M\u00e1s tiempo en familia<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mayor acumulaci\u00f3n de riqueza<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Jubilaciones m\u00e1s largas<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mayores oportunidades personales<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Por el contrario, el entusiasmo se debilita entre los grupos cuya conexi\u00f3n con las estructuras econ\u00f3micas tradicionales es menos segura.<\/span><\/p>\n<h3><b>Las mujeres se muestran ligeramente m\u00e1s a favor<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Otro hallazgo notable es la modesta brecha de g\u00e9nero.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las mujeres expresan un apoyo ligeramente mayor que los hombres. Esto desaf\u00eda los estereotipos de que el entusiasmo por las tecnolog\u00edas de prolongaci\u00f3n de la vida est\u00e1 impulsado principalmente por futuristas y entusiastas de la tecnolog\u00eda del g\u00e9nero masculino. La explicaci\u00f3n m\u00e1s probable radica en el enfoque. Una vida m\u00e1s larga y saludable resulta atractiva no solo como un logro tecnol\u00f3gico, sino tambi\u00e9n como una mejora en la calidad de vida, un tema familiar y una cuesti\u00f3n de cuidado de otras personas.<\/span><\/p>\n<h3><b>Los ingresos dan una sorpresa<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Quiz\u00e1s el resultado m\u00e1s inesperado se refiere a los ingresos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las personas con ingresos m\u00e1s altos son, de hecho, el grupo menos favorable. Este hallazgo desaf\u00eda la suposici\u00f3n de que el entusiasmo por la longevidad aumenta a medida que aumenta la riqueza. Una posibilidad es que las personas con ingresos m\u00e1s altos piensen m\u00e1s en las consecuencias sist\u00e9micas y la disrupci\u00f3n institucional. Otra es que ya disfrutan de un mayor control sobre su tiempo, lo que reduce la urgencia percibida de la extensi\u00f3n de la vida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Independientemente de la explicaci\u00f3n, el apoyo no es simplemente una preferencia de lujo de las \u00e9lites.<\/span><\/p>\n<h3><b>Las ciudades se muestran m\u00e1s entusiastas, pero no de manera espectacular<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Los residentes urbanos muestran el mayor apoyo. Esto refleja patrones m\u00e1s amplios observados en las actitudes hacia la ciencia y la innovaci\u00f3n. Sin embargo, la brecha sigue siendo relativamente modesta. Los encuestados rurales siguen mostrando claramente una actitud positiva neta, lo que sugiere que el atractivo de la longevidad saludable se extiende mucho m\u00e1s all\u00e1 de los centros urbanos de innovaci\u00f3n.<\/span><\/p>\n<h2><b>Lo que esto significa para el movimiento de la longevidad<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La lecci\u00f3n central de la encuesta es que el p\u00fablico apoya m\u00e1s el \u201ctiempo de vida saludable\u201d que el \u201ctiempo de vida total\u201d. La gran mayor\u00eda de las personas comprende el atractivo de mantenerse sano por m\u00e1s tiempo. Lo que a\u00fan no han decidido es si extender radicalmente la vida humana mejorar\u00eda la sociedad. Esta distinci\u00f3n es importante. Durante d\u00e9cadas, los defensores de la longevidad han enfatizado a menudo el extraordinario potencial de extender la esperanza de vida. Sin embargo, los datos sugieren que el discurso p\u00fablico m\u00e1s persuasivo podr\u00eda ser mucho m\u00e1s sencillo: la gente quiere menos a\u00f1os de enfermedad, fragilidad, discapacidad y deterioro cognitivo. Este mensaje goza de un amplio atractivo intuitivo. El desaf\u00edo para este campo es que el \u00e9xito t\u00e9cnico por s\u00ed solo tal vez no genere legitimidad p\u00fablica. Los avances futuros deber\u00e1n responder preguntas sobre equidad, accesibilidad, asequibilidad y consecuencias sociales de manera tan convincente como responden a las preguntas biol\u00f3gicas sobre el envejecimiento.<\/span><\/p>\n<h2><b>Conclusi\u00f3n<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">El mundo se muestra cautelosamente abierto a la extensi\u00f3n radical de la vida. El apoyo existe en todas las grandes regiones, abarca a todos los grupos de edad y supera a la oposici\u00f3n a nivel mundial. Pero el entusiasmo sigue siendo menor de lo que muchos defensores suponen. La encuesta sugiere que a las personas les atrae la promesa de vidas m\u00e1s largas y saludables, pero siguen sin estar seguras de lo que significar\u00eda para la sociedad un futuro mucho m\u00e1s largo. En resumen, el p\u00fablico parece estar listo para la medicina de la longevidad.<\/span><\/p>\n<hr \/>\n<p><span style=\"font-weight: 400;\">La buena noticia del mes: <\/span><a href=\"https:\/\/www.nature.com\/articles\/d41586-026-01836-7#author-0\"><span style=\"font-weight: 400;\">el primer ensayo de reprogramaci\u00f3n celular del mundo<\/span><\/a><\/p>\n<hr \/>\n<p>En un hito sin precedentes a nivel mundial para la biotecnolog\u00eda de la longevidad, el primer paciente ha recibido una terapia de reprogramaci\u00f3n celular parcial dise\u00f1ada para que las c\u00e9lulas envejecidas se comporten como las m\u00e1s j\u00f3venes. El ensayo cl\u00ednico, dirigido por Life Biosciences, est\u00e1 evaluando si tres genes de rejuvenecimiento pueden regenerar las c\u00e9lulas da\u00f1adas del nervio \u00f3ptico en pacientes con glaucoma, lo que marca la primera prueba en humanos de una tecnolog\u00eda que muchos investigadores creen que alg\u00fan d\u00eda podr\u00eda transformar la medicina relacionada con el envejecimiento.<\/p>\n<hr \/>\n<p><span style=\"font-weight: 400;\">Noticias de Heales y la comunidad de la longevidad: <\/span><span style=\"font-weight: 400;\">Asamblea sobre Envejecimiento Saludable y Longevidad 2026<\/span><\/p>\n<hr \/>\n<p><span style=\"font-weight: 400;\">La Asamblea sobre Envejecimiento Saludable y Longevidad 2026 reuni\u00f3 a cient\u00edficos, m\u00e9dicos, responsables de pol\u00edticas y l\u00edderes comunitarios de toda Lituania en una serie de eventos de una semana de duraci\u00f3n dedicados a promover la longevidad saludable. La asamblea destac\u00f3 el creciente impulso que est\u00e1n cobrando la medicina de la longevidad basada en la evidencia, la investigaci\u00f3n sobre el envejecimiento y las pol\u00edticas intersectoriales destinadas a prolongar la vida saludable en Europa y m\u00e1s all\u00e1.<\/span><\/p>\n<hr \/>\n<p><span style=\"font-weight: 400;\">Para m\u00e1s informaci\u00f3n:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/heales.org\/\"><span style=\"font-weight: 400;\">Heales<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><a href=\"https:\/\/www.levf.org\/\"><span style=\"font-weight: 400;\">Fundaci\u00f3n Longevity Escape Velocity<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><a href=\"https:\/\/longevityalliance.org\/\"><span style=\"font-weight: 400;\">Alianza Internacional para la Longevidad<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><a href=\"http:\/\/longecity.org\/\"><span style=\"font-weight: 400;\">Longecity<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><a href=\"http:\/\/lifespan.io\/\"><span style=\"font-weight: 400;\">Lifespan.io<\/span><\/a><span style=\"font-weight: 400;\"> y <\/span><a href=\"https:\/\/agingbiotech.info\/\"><span style=\"font-weight: 400;\">biotecnolog\u00eda del envejecimiento<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/heales.org\/\"><span style=\"font-weight: 400;\">Noticias cient\u00edficas mensuales de Heales<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.youtube.com\/@HealesMovies\"><span style=\"font-weight: 400;\">Canal de YouTube de Heales<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"mailto:info@heales.org\"><span style=\"font-weight: 400;\">Cont\u00e1ctanos<\/span><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Creo que el envejecimiento es una enfermedad. Creo que es tratable. Creo que podemos tratarla durante nuestras vidas. (&#8230;) No importa que podamos prolongar la esperanza de vida si no podemos prolongar la esperanza de vida saludable en la misma medida. David Sinclair (bi\u00f3logo australiano) Fuente Tema de este mes: Resultados de la encuesta sobre &hellip; <a href=\"https:\/\/heales.org\/healeses\/2026\/06\/29\/boletin-mensual-de-heales-la-muerte-de-la-muerte-n-o-206\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Bolet\u00edn mensual de Heales La muerte de la muerte N.\u00ba 206<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":597,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6],"tags":[8],"class_list":["post-596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletin-mensual","category-la-muerte-de-la-muerte","tag-featured"],"_links":{"self":[{"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/posts\/596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/comments?post=596"}],"version-history":[{"count":1,"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/posts\/596\/revisions"}],"predecessor-version":[{"id":598,"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/posts\/596\/revisions\/598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/media\/597"}],"wp:attachment":[{"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/media?parent=596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/categories?post=596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/heales.org\/healeses\/wp-json\/wp\/v2\/tags?post=596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}